{"id":1465,"date":"2018-03-27T07:23:40","date_gmt":"2018-03-27T10:23:40","guid":{"rendered":"http:\/\/www.abrazpe.org.br\/?p=1465"},"modified":"2018-03-27T07:23:40","modified_gmt":"2018-03-27T10:23:40","slug":"porto-do-acu-pede-isonomia-celebra-zpe-e-servico-door-to-door","status":"publish","type":"post","link":"https:\/\/www.abrazpe.org.br\/index.php\/2018\/03\/27\/porto-do-acu-pede-isonomia-celebra-zpe-e-servico-door-to-door\/","title":{"rendered":"Porto do A\u00e7u pede isonomia, celebra ZPE e servi\u00e7o door to door"},"content":{"rendered":"<p class=\"estimated-read-time\">Tempo de leitura:<small> menos de 1 minuto<\/small><\/p> <p>O Porto do A\u00e7u, localizado no litoral norte do estado do Rio de Janeiro, planeja pol\u00edticas comerciais agressivas para a atra\u00e7\u00e3o de novas cargas e empreendimentos para a regi\u00e3o.<\/p>\n<p>Durante a <a href=\"https:\/\/portogente.com.br\/radar-global\/100439-mudancas-na-intermodal-permitem-tracar-panorama-da-logistica-no-brasil\">realiza\u00e7\u00e3o da feira Intermodal South America 2018<\/a>, o gerente de Rela\u00e7\u00f5es Institucionais do Porto do A\u00e7u, Caio Cunha, disse ao <strong>Portogente<\/strong> que\u00a0os portos privados s\u00e3o o &#8220;caminho do crescimento da \u00e1rea portu\u00e1ria e log\u00edstica no Pa\u00eds&#8221;. Representando os interesses do setor, ele exige isonomia na competi\u00e7\u00e3o com os portos p\u00fablicos, j\u00e1 que os TUPs precisam arcar com investimentos pr\u00f3prios em infraesturura e dragagem.<\/p>\n<p>Na mesma ocasi\u00e3o, Joyce Merc\u00eas, especialista de Parcerias Estrat\u00e9gicas do Porto do A\u00e7u, falou ao <strong>Portogente<\/strong> sobre a <a href=\"https:\/\/portogente.com.br\/radar-global\/98994-temer-assina-pessoalmente-zpe-porto-do-acu-pescados-brasileiros-nao-serao-exportados-e-revisao-de-norma-pela-antaq\">aprova\u00e7\u00e3o da Zona de Processamento de Exporta\u00e7\u00e3o (ZPE) na regi\u00e3o<\/a> e do servi\u00e7o porta a porta oferecido aos clientes.<\/p>\n<p><a href=\"https:\/\/portogente.com.br\/radar-global\/100691-porto-do-acu-pede-isonomia-celebra-zpe-e-servico-door-to-door\">Leia mais<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><small> menos de 1 minuto<\/small> O Porto do A\u00e7u, localizado no litoral norte do estado do Rio de Janeiro, planeja pol\u00edticas comerciais agressivas para a atra\u00e7\u00e3o de novas cargas e empreendimentos para a regi\u00e3o. Durante a realiza\u00e7\u00e3o da feira Intermodal South America 2018, o gerente de Rela\u00e7\u00f5es Institucionais do Porto do A\u00e7u, Caio Cunha, disse ao Portogente que\u00a0os portos privados s\u00e3o o &#8220;caminho do crescimento da \u00e1rea portu\u00e1ria e log\u00edstica no Pa\u00eds&#8221;. Representando os interesses do setor, ele exige isonomia na competi\u00e7\u00e3o com os portos <a href=\"https:\/\/www.abrazpe.org.br\/index.php\/2018\/03\/27\/porto-do-acu-pede-isonomia-celebra-zpe-e-servico-door-to-door\/\" class=\"more-link\"><span>Continue lendo<\/span>\u2192<\/a><\/p>\n","protected":false},"author":4,"featured_media":600,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["entry","author-adm_hb2018","post-1465","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/1465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=1465"}],"version-history":[{"count":1,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/1465\/revisions"}],"predecessor-version":[{"id":1466,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/1465\/revisions\/1466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media\/600"}],"wp:attachment":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=1465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=1465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=1465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}