{"id":1480,"date":"2018-04-02T09:15:38","date_gmt":"2018-04-02T12:15:38","guid":{"rendered":"http:\/\/www.abrazpe.org.br\/?p=1480"},"modified":"2018-04-02T09:15:38","modified_gmt":"2018-04-02T12:15:38","slug":"zpe-duas-empresas-japonesas-buscam-o-estado-do-ceara","status":"publish","type":"post","link":"https:\/\/www.abrazpe.org.br\/index.php\/2018\/04\/02\/zpe-duas-empresas-japonesas-buscam-o-estado-do-ceara\/","title":{"rendered":"ZPE: Duas empresas japonesas buscam o Estado do Cear\u00e1"},"content":{"rendered":"<p class=\"estimated-read-time\">Tempo de leitura:<small> 2 minutos<\/small><\/p> <p>Duas empresas japonesas do ramo de tubula\u00e7\u00f5es e f\u00e1rmacos procuraram o governo cearense na \u00faltima semana em busca de informa\u00e7\u00f5es sobre a Zona de Processamento de Exporta\u00e7\u00e3o (ZPE) do Cear\u00e1, de acordo com o secret\u00e1rio Antonio Balhmann (Assuntos Internacionais). O Jap\u00e3o \u00e9 o novo alvo do Estado na capta\u00e7\u00e3o de mais investidores para o Complexo Industrial e Portu\u00e1rio do Pec\u00e9m (Cipp), especialmente, a ZPE.<\/p>\n<p>&#8220;Elas procuraram se antecipar aos demais que vamos receber nesta semana&#8221;, afirmou o secret\u00e1rio, relembrando que nos dias 6 e 7 o governador Camilo Santana recebe uma comitiva de 30 empres\u00e1rios organizada pela C\u00e2mara de Com\u00e9rcio e Ind\u00fastria Japonesa no Brasil.<\/p>\n<p>Nesse grupo devem vir ainda, segundo ele, representantes de empresas de setores agr\u00edcola, metalmec\u00e2nico e autope\u00e7as. Ap\u00f3s o semin\u00e1rio intitulado &#8220;ZPE do Cear\u00e1 e as oportunidades de investimentos no Estado&#8221;, Balhmann conta que ambas devem partir para tratativas mais diretas, onde os investimentos devem ser negociados.<\/p>\n<p>Um dos objetivos de atrair novas empresas \u00e9 captar ind\u00fastrias para o Setor II da ZPE, no qual est\u00e1 sendo trabalhada uma \u00e1rea de 150 hectares de alfandegamento junto \u00e0 Receita Federal e que deve dotar a Zona de maior capacidade de acolhimento de empresas voltadas \u00e0s exporta\u00e7\u00f5es. Ao todo, s\u00e3o disponibilizados 2 mil hectares para a implanta\u00e7\u00e3o das unidades fabris.<\/p>\n<p>Os japoneses devem conferir toda a estrutura no dia 7 de abril, quando uma visita est\u00e1 programada para o Cipp, na qual eles devem ir at\u00e9 o Porto do Pec\u00e9m tamb\u00e9m. J\u00e1 no dia do semin\u00e1rio, dia 6 de abril, o governador Camilo Santana ter\u00e1 ainda um encontro com o embaixador do Jap\u00e3o no Brasil, Akira Yamada.<\/p>\n<p>&#8220;Tivemos, no passado, no governo do ent\u00e3o governador Ciro Gomes, trabalhado em duas frentes com os japoneses: na pesca do atum, considerando que tinham mais de cem barcos japoneses pescando entre Nordeste brasileiro e a \u00c1frica, no golfo da Guin\u00e9; e no polo t\u00eaxtil, buscando atrair japoneses com sinergia com essa nossa voca\u00e7\u00e3o&#8221;, relembrou Balhmann sobre quando captou a YKK para o Polo Industrial de Maracana\u00fa.<\/p>\n<p>Agora, com o apoio da diretoria de Assuntos Internacionais do Senado Federal, o secret\u00e1rio diz ter mais oportunidades de sucesso. A confian\u00e7a vem de o Estado possuir na vitrine de neg\u00f3cios empreendimentos consolidados como a Companhia Sider\u00fargica do Pec\u00e9m (CSP) &#8211; fruto de neg\u00f3cios com duas empresas sul-coreanas &#8211; e o projeto da refinaria com os chineses, que, segundo ele, deve render bons resultados ainda neste ano.<\/p>\n<p><a href=\"http:\/\/diariodonordeste.verdesmares.com.br\/cadernos\/negocios\/zpe-2-japonesas-buscam-o-estado-1.1917187\">Leia mais<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><small> 2 minutos<\/small> Duas empresas japonesas do ramo de tubula\u00e7\u00f5es e f\u00e1rmacos procuraram o governo cearense na \u00faltima semana em busca de informa\u00e7\u00f5es sobre a Zona de Processamento de Exporta\u00e7\u00e3o (ZPE) do Cear\u00e1, de acordo com o secret\u00e1rio Antonio Balhmann (Assuntos Internacionais). O Jap\u00e3o \u00e9 o novo alvo do Estado na capta\u00e7\u00e3o de mais investidores para o Complexo Industrial e Portu\u00e1rio do Pec\u00e9m (Cipp), especialmente, a ZPE. &#8220;Elas procuraram se antecipar aos demais que vamos receber nesta semana&#8221;, afirmou o secret\u00e1rio, relembrando que nos dias <a href=\"https:\/\/www.abrazpe.org.br\/index.php\/2018\/04\/02\/zpe-duas-empresas-japonesas-buscam-o-estado-do-ceara\/\" class=\"more-link\"><span>Continue lendo<\/span>\u2192<\/a><\/p>\n","protected":false},"author":4,"featured_media":1276,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["entry","author-adm_hb2018","post-1480","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/1480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=1480"}],"version-history":[{"count":1,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/1480\/revisions"}],"predecessor-version":[{"id":1481,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/1480\/revisions\/1481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media\/1276"}],"wp:attachment":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=1480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=1480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=1480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}