{"id":2287,"date":"2018-09-02T08:40:53","date_gmt":"2018-09-02T11:40:53","guid":{"rendered":"http:\/\/www.abrazpe.org.br\/?p=2287"},"modified":"2018-09-02T08:42:55","modified_gmt":"2018-09-02T11:42:55","slug":"revista-do-financial-times-destaca-capacidade-economica-de-uberaba","status":"publish","type":"post","link":"https:\/\/www.abrazpe.org.br\/index.php\/2018\/09\/02\/revista-do-financial-times-destaca-capacidade-economica-de-uberaba\/","title":{"rendered":"Revista do Financial Times destaca capacidade econ\u00f4mica de Uberaba"},"content":{"rendered":"<p class=\"estimated-read-time\">Tempo de leitura:<small> 2 minutos<\/small><\/p> <p>A cidade de Uberaba foi tema de mat\u00e9ria na revista fDi Magazine, com foco no desenvolvimento econ\u00f4mico. A revista pertence ao grupo Financial Times, sendo direcionada para investidores estrangeiros ao redor do mundo. A equipe da revista se interessou por Uberaba ap\u00f3s conhecer os projetos da cidade, como a ZPE (Zona de Processamento de Exporta\u00e7\u00e3o), Aeroporto Internacional de Cargas e Passageiros, Intervales, bem como as oportunidades oferecidas pelo munic\u00edpio no que tange \u00e0 capacidade log\u00edstica, distritos industriais, Porto Seco, Lei de Incentivo e Parque Tecnol\u00f3gico.<\/p>\n<p>Segundo o prefeito Paulo Piau, Uberaba avan\u00e7a na sua internacionaliza\u00e7\u00e3o. \u201cO que est\u00e1 na mat\u00e9ria s\u00e3o as nossas potencialidades, como foi dito: do Zebu ao Tattoo, ao se referir \u00e0 tinta para tatuagem produzida em Uberaba e que \u00e9 exportada para o mundo todo. E mais que isso, o que temos a oferecer em termos de desenvolvimento econ\u00f4mico \u00e9 compat\u00edvel com os interesses dos investidores, que s\u00e3o os leitores desta revista. Eles nos procuraram para conhecer a cidade e as oportunidades oferecidas, pois entendem que estas informa\u00e7\u00f5es est\u00e3o alinhadas com o objetivo da revista. Todos n\u00f3s, uberabenses, temos que nos orgulhar, pois trabalhamos aqui, vivemos aqui e cuidamos desta cidade. \u00c9 motivo de orgulho\u201d, afirmou.<\/p>\n<p>A equipe do Financial Times conheceu as potencialidades de Uberaba e os projetos durante agenda do ex-secret\u00e1rio de Comunica\u00e7\u00e3o Denis Silva e de Jos\u00e9 Renato Gomes, secret\u00e1rio de Desenvolvimento Econ\u00f4mico, em Dubai, nos Emirados \u00c1rabes. Eles participavam\u00a0da 4\u00aa Confer\u00eancia Internacional da World Free Zones Organization,\u00a0promovida pelo\u00a0Minist\u00e9rio da Ind\u00fastria, Com\u00e9rcio Exterior e Servi\u00e7os (MDIC). No local apresentaram as propostas de Uberaba. \u201cCobra que n\u00e3o rasteja n\u00e3o engole sapo. \u00c9 um velho ditado, mas verdadeiro. Quando uma agenda internacional \u00e9 bem feita, d\u00e1 resultado. Foi assim em Dubai e tamb\u00e9m quando fomos \u00e0 R\u00fassia e China. Temos que correr atr\u00e1s, que as oportunidades v\u00e3o surgir. N\u00e3o tenho d\u00favida de que o impacto desta reportagem ser\u00e1 positivo, assim como foram estas viagens\u201d, afirmou Piau.<\/p>\n<p>O secret\u00e1rio Jos\u00e9 Renato lembra que, quando da vinda a Uberaba do rep\u00f3rter da revista, a Sedec ofereceu todas as informa\u00e7\u00f5es, bem como contatos das empresas da cidade, para que o mesmo pudesse buscar informa\u00e7\u00f5es mais t\u00e9cnicas e imparciais. \u201cFizemos nosso papel. Mostramos o que temos. Apresentamos nos m\u00ednimos detalhes nossos projetos, nossas expectativas, as legisla\u00e7\u00f5es existentes e fizemos quest\u00e3o de atender da melhor forma poss\u00edvel a todos os questionamentos. Uberaba fazer parte desta revista \u00e9 o mesmo que estar na vitrine do mundo dos neg\u00f3cios. As informa\u00e7\u00f5es ser\u00e3o lidas por quem busca oportunidade de investimento, ou seja, pelas empresas que t\u00eam dinheiro e que buscam projetos para investir. Queremos gerar emprego e renda \u00e0 popula\u00e7\u00e3o e, para isso, Uberaba se mostra preparada para receber investimento do mundo todo. Temos projeto e capacidade para isto\u201d, finalizou.<\/p>\n<p><a href=\"https:\/\/www.jmonline.com.br\/novo\/?noticias,6,POL\u00cdTICA,165332\">Leia mais<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><small> 2 minutos<\/small> A cidade de Uberaba foi tema de mat\u00e9ria na revista fDi Magazine, com foco no desenvolvimento econ\u00f4mico. A revista pertence ao grupo Financial Times, sendo direcionada para investidores estrangeiros ao redor do mundo. A equipe da revista se interessou por Uberaba ap\u00f3s conhecer os projetos da cidade, como a ZPE (Zona de Processamento de Exporta\u00e7\u00e3o), Aeroporto Internacional de Cargas e Passageiros, Intervales, bem como as oportunidades oferecidas pelo munic\u00edpio no que tange \u00e0 capacidade log\u00edstica, distritos industriais, Porto Seco, Lei de Incentivo <a href=\"https:\/\/www.abrazpe.org.br\/index.php\/2018\/09\/02\/revista-do-financial-times-destaca-capacidade-economica-de-uberaba\/\" class=\"more-link\"><span>Continue lendo<\/span>\u2192<\/a><\/p>\n","protected":false},"author":4,"featured_media":1114,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["entry","author-adm_hb2018","post-2287","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/2287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=2287"}],"version-history":[{"count":1,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/2287\/revisions"}],"predecessor-version":[{"id":2289,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/2287\/revisions\/2289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media\/1114"}],"wp:attachment":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=2287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=2287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=2287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}