{"id":2809,"date":"2019-03-25T20:45:45","date_gmt":"2019-03-25T23:45:45","guid":{"rendered":"http:\/\/www.abrazpe.org.br\/?p=2809"},"modified":"2019-03-25T20:45:51","modified_gmt":"2019-03-25T23:45:51","slug":"novos-investimentos-alimentam-expectativas-ceara","status":"publish","type":"post","link":"https:\/\/www.abrazpe.org.br\/index.php\/2019\/03\/25\/novos-investimentos-alimentam-expectativas-ceara\/","title":{"rendered":"Novos investimentos alimentam expectativas &#8211; Cear\u00e1"},"content":{"rendered":"<p class=\"estimated-read-time\">Tempo de leitura:<small> 2 minutos<\/small><\/p> \n<p>Assim como ocorreu com a Companhia Sider\u00fargica do Pec\u00e9m (CSP), outros investimentos que chegam ao Cear\u00e1 trazem consigo a expectativa de mais neg\u00f3cios em cadeia capazes de impulsionar a economia cearense. Ao contr\u00e1rio dos restaurantes e outros pequenos com\u00e9rcios, como ocorreu em Cumbuco, parcerias como a da alem\u00e3 Fraport AG e da holandesa Porto de Roterd\u00e3 alimentam a esperan\u00e7a de mais crescimento para o Estado.<\/p>\n\n\n\n<p>Segundo R\u00f4mulo Alexandre Soares, presidente do Conselho de Rela\u00e7\u00f5es Internacionais da Federa\u00e7\u00e3o das Ind\u00fastrias do Estado do Cear\u00e1 (FIEC), bons neg\u00f3cios podem surgir a partir do aproveitamento do que o Estado j\u00e1 oferece em termos de mat\u00e9ria-prima. &#8220;Quem vier l\u00e1 de fora vai tentar investir onde o Cear\u00e1 tem voca\u00e7\u00e3o. Precisamos pensar se temos voca\u00e7\u00e3o para investir em certas \u00e1reas. Se n\u00f3s n\u00e3o tiv\u00e9ssemos um vento bom, n\u00e3o ter\u00edamos investimentos em energia e\u00f3lica, por exemplo&#8221;.<\/p>\n\n\n\n<p>Ele acredita que o dever de casa vem sendo feito. A gest\u00e3o do Aeroporto Internacional Pinto Martins pela Fraport AG, por exemplo, \u00e9 essencial para que o Cear\u00e1 se mantenha conectado a outras regi\u00f5es do mundo e, assim, continue a ser visto por investidores estrangeiros. Para exemplificar a import\u00e2ncia dessa conex\u00e3o, ele lembra do impacto causado pelo voo Fortaleza-Lisboa, inaugurado pela TAP Air Portugal, que completou 21 anos.<\/p>\n\n\n\n<p>&#8220;N\u00e3o tenho d\u00favidas de que a nossa vantagem em rela\u00e7\u00e3o ao turismo est\u00e1 associada a esses voos di\u00e1rios, que foram respons\u00e1veis pelas quase 1.000 empresas de capital portugu\u00eas instaladas no Cear\u00e1. Isso pode ocorrer com cada um dos lugares que o Cear\u00e1 pode se conectar? No caso portugu\u00eas, deu certo. Em rela\u00e7\u00e3o ao hub, as liga\u00e7\u00f5es a\u00e9reas podem ajudar a desenvolver nossas vantagens naquilo que somos competitivos&#8221;, avalia.<\/p>\n\n\n\n<p>O Porto de Roterd\u00e3 \u00e9 outra novidade que abre possibilidades de neg\u00f3cios em diferentes frentes. Em parceria com a Companhia de Desenvolvimento do Complexo Industrial e Portu\u00e1rio do Pec\u00e9m S.A. (Cipp S. A.), a chegada da empresa holandesa abre caminho n\u00e3o s\u00f3 para novas linhas e cargas para o Porto do Pec\u00e9m, mas tamb\u00e9m para novas ind\u00fastrias que venham integrar a Zona de Processamento e Exporta\u00e7\u00e3o (ZPE). A participa\u00e7\u00e3o holandesa no complexo envolve investimento de 30% nas a\u00e7\u00f5es da CIPP S.A., no valor de R$ 323 milh\u00f5es.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.opovo.com.br\/jornal\/economia\/2019\/03\/23\/novos-investimentos-alimentam-expectativas.html\">Leia mais<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><small> 2 minutos<\/small> Assim como ocorreu com a Companhia Sider\u00fargica do Pec\u00e9m (CSP), outros investimentos que chegam ao Cear\u00e1 trazem consigo a expectativa de mais neg\u00f3cios em cadeia capazes de impulsionar a economia cearense. Ao contr\u00e1rio dos restaurantes e outros pequenos com\u00e9rcios, como ocorreu em Cumbuco, parcerias como a da alem\u00e3 Fraport AG e da holandesa Porto de Roterd\u00e3 alimentam a esperan\u00e7a de mais crescimento para o Estado. Segundo R\u00f4mulo Alexandre Soares, presidente do Conselho de Rela\u00e7\u00f5es Internacionais da Federa\u00e7\u00e3o das Ind\u00fastrias do Estado do <a href=\"https:\/\/www.abrazpe.org.br\/index.php\/2019\/03\/25\/novos-investimentos-alimentam-expectativas-ceara\/\" class=\"more-link\"><span>Continue lendo<\/span>\u2192<\/a><\/p>\n","protected":false},"author":4,"featured_media":2066,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["entry","author-adm_hb2018","post-2809","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/2809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=2809"}],"version-history":[{"count":1,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/2809\/revisions"}],"predecessor-version":[{"id":2810,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/2809\/revisions\/2810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media\/2066"}],"wp:attachment":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=2809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=2809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=2809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}