{"id":3344,"date":"2019-11-17T13:52:28","date_gmt":"2019-11-17T16:52:28","guid":{"rendered":"https:\/\/www.abrazpe.org.br\/?p=3344"},"modified":"2019-11-17T13:52:37","modified_gmt":"2019-11-17T16:52:37","slug":"zones-franches-africaines-faut-il-renoncer-aux-rentrees-fiscales-pour-industrialiser-et-creer-des-emplois","status":"publish","type":"post","link":"https:\/\/www.abrazpe.org.br\/index.php\/2019\/11\/17\/zones-franches-africaines-faut-il-renoncer-aux-rentrees-fiscales-pour-industrialiser-et-creer-des-emplois\/","title":{"rendered":"Zones franches africaines: faut-il renoncer aux rentr\u00e9es fiscales pour industrialiser et cr\u00e9er des emplois?"},"content":{"rendered":"<p class=\"estimated-read-time\">Tempo de leitura:<small> 7 minutos<\/small><\/p> \n<p>Les premi\u00e8res zones \u00e9conomiques sp\u00e9ciales (ZES) et les zones franches ont \u00e9t\u00e9 mises en place en Afrique, \u00e0 partir des ann\u00e9es 70, suite \u00e0 leur succ\u00e8s dans nombreux pays asiatiques o\u00f9 elles avaient facilit\u00e9 l\u2019industrialisation.<\/p>\n\n\n\n<p>Cette strat\u00e9gie a connu un regain d\u2019int\u00e9r\u00eat en Afrique, au cours des derni\u00e8res ann\u00e9es. D\u2019apr\u00e8s l\u2019Organisation internationale du travail (OIT), on d\u00e9nombrait en 1997, seulement 47 zones franches sur l\u2019ensemble du continent africain. Aujourd\u2019hui, on d\u00e9nombre plus de 200 zones \u00e9conomiques sp\u00e9ciales et zones franches, \u00e0 travers le continent, selon l\u2019Organisation africaine des zones franches (AFZO).<\/p>\n\n\n\n<p>En 2011, le Gabon a inaugur\u00e9 la Zone \u00e9conomique sp\u00e9ciale de Nkok, s\u2019\u00e9talant sur 1390 hectares, \u00e0 27 km de Libreville.&nbsp;Co\u00fbt global de la r\u00e9alisation des travaux&nbsp;: 425 millions&nbsp;$.<\/p>\n\n\n\n<p>La m\u00eame ann\u00e9e, le Maroc a mis en place la Midparc, une zone franche s\u2019\u00e9tendant sur 124,4 ha, non loin de l\u2019a\u00e9roport de Casablanca.<\/p>\n\n\n\n<p>En 2013, c\u2019est l\u2019Ethiopie qui annon\u00e7ait l\u2019ouverture de la Bole Lemi Industrial Zone, sa toute premi\u00e8re ZES s\u2019\u00e9talant sur 156 ha pr\u00e8s d\u2019Addis-Abeba, pour un co\u00fbt de 49 millions&nbsp;$.<\/p>\n\n\n\n<p>L\u2019ann\u00e9e derni\u00e8re, Djibouti lan\u00e7ait sa zone franche internationale (DIFTZ) consid\u00e9r\u00e9e comme la plus grande d\u2019Afrique. Sa construction, pr\u00e9vue pour s\u2019\u00e9taler sur 10 ans, devrait couvrir une superficie de 4800 hectares, pour un investissement total estim\u00e9 \u00e0 3,5 milliards&nbsp;$.<\/p>\n\n\n\n<p>Les prochaines ann\u00e9es devraient aussi voir arriver de nouvelles ZES et zones franches, sp\u00e9cialis\u00e9es parfois dans le secteur agricole, manufacturier ou m\u00eame des t\u00e9l\u00e9communications. En juin dernier, par exemple, le gouvernement \u00e9gyptien annon\u00e7ait qu\u2019il construirait six nouvelles zones franches dans le pays, d\u2019ici \u00e0 la fin de l\u2019ann\u00e9e 2020.<\/p>\n\n\n\n<p>En Ouganda, le gouvernement compte construire au cours des prochaines ann\u00e9es une zone franche agricole s\u2019\u00e9tendant sur 2500 hectares et une autre \u00e0 l\u2019a\u00e9roport international d\u2019Entebbe.<\/p>\n\n\n\n<p>Gr\u00e2ce notamment aux avantages fiscaux qu\u2019elles offrent, ces structures attirent des entreprises internationales qui cherchent \u00e0 s\u2019\u00e9tendre dans de nombreux pays. De ce fait, l\u2019introduction sur les march\u00e9s africains de ces nouveaux acteurs augmente la production nationale et la diversifie tout en ayant un impact majeur sur la r\u00e9duction du ch\u00f4mage, surtout dans les secteurs manufacturier et agricole.<\/p>\n\n\n\n<p>A Djibouti, par exemple, un rapport du FDI Intelligence estime que la seule phase pilote de la DIFTZ a permis d&#8217;augmenter le PIB du pays de 11%. Au cours des 10 prochaines ann\u00e9es, la zone devrait g\u00e9n\u00e9rer plus de 350&nbsp;000 emplois. Un v\u00e9ritable coup d\u2019arr\u00eat \u00e0 l\u2019\u00e9volution du taux de ch\u00f4mage qui avait atteint 39% en 2015, dans un pays qui compte \u00e0 peine 1 million d\u2019habitants.<\/p>\n\n\n\n<p>Le rapport indique \u00e9galement qu\u2019au Gabon, la ZES de&nbsp; Nkok g\u00e9n\u00e8re actuellement pr\u00e8s de 5000 emplois directs et autant d&#8217;emplois indirects. La zone repr\u00e9sente 38% du total des conteneurs export\u00e9s du pays et a connu des flux cumul\u00e9s d&#8217;IDE de pr\u00e8s de 1,7 milliard de dollars.<\/p>\n\n\n\n<p>Au Maroc, la zone franche Tanger Med, situ\u00e9e au sein du complexe portuaire de Tanger, le plus important d\u2019Afrique, a permis au pays d\u2019attirer plus de 900 entreprises multinationales, de plus de 30 nationalit\u00e9s diff\u00e9rentes. Dans un pays comptant plus de 36 millions d\u2019habitants avec un taux de ch\u00f4mage des jeunes, estim\u00e9 \u00e0 plus de 25%, plus de 90&nbsp;000 emplois ont \u00e9t\u00e9 cr\u00e9\u00e9s gr\u00e2ce \u00e0 cette structure. En attirant des poids lourds du secteur automobile, tels que les fran\u00e7ais Renault et PSA, le pays d\u2019Afrique du Nord a r\u00e9ussi \u00e0 devenir, en quelques ann\u00e9es, l\u2019un des principaux hubs du secteur, sur le continent. D\u2019apr\u00e8s FDI Intelligence, Tanger Med accueille une usine de l\u2019Alliance Renault-Nissan-Mitsubishi, qui est la plus grande usine automobile d&#8217;Afrique, avec une capacit\u00e9 de production totale de 450&nbsp;000 voitures par an.<\/p>\n\n\n\n<p>Si elles ont l\u2019avantage d\u2019attirer de nombreuses entreprises \u00e9trang\u00e8res dans les pays o\u00f9 elles sont mises en place, et de cr\u00e9er de nombreux emplois, les zones franches constituent \u00e9galement une importante perte de recettes fiscales pour les Etats. Alors que les pays africains sont appel\u00e9s \u00e0 am\u00e9liorer la collecte de leurs recettes fiscales pour r\u00e9aliser les investissements n\u00e9cessaires \u00e0 la r\u00e9duction de la pauvret\u00e9 sur le continent, de nombreuses organisations d\u00e9noncent cette situation.<\/p>\n\n\n\n<p>Au Maroc, par exemple, l\u2019ONG Oxfam indiquait dans un rapport paru en d\u00e9but d\u2019ann\u00e9e, que les incitations fiscales pratiqu\u00e9es dans les zones franches en faveur des multinationales, faisaient perdre d\u2019\u00e9normes ressources financi\u00e8res au pays. De ce fait, une grande partie de l\u2019activit\u00e9 \u00e9conomique \u00e9chappe \u00e0 l\u2019imp\u00f4t sur les soci\u00e9t\u00e9s contribuant ainsi \u00e0 accentuer les in\u00e9galit\u00e9s dans le pays.<\/p>\n\n\n\n<p>Gr\u00e2ce aux zones franches et offshores cr\u00e9\u00e9es dans le pays, les entreprises dont une grande partie vient de l\u2019\u00e9tranger, b\u00e9n\u00e9ficient d\u2019une exon\u00e9ration de l\u2019imp\u00f4t sur les soci\u00e9t\u00e9s pendant les cinq premi\u00e8res ann\u00e9es d\u2019exercice, et le taux n\u2019est que de 8,75%, les vingt ann\u00e9es suivantes.<\/p>\n\n\n\n<p><em>\u00abDes&nbsp; multinationales&nbsp; \u00e9trang\u00e8res&nbsp; b\u00e9n\u00e9ficient&nbsp; de&nbsp; cet&nbsp; avantage fiscal.&nbsp; La&nbsp; contrepartie&nbsp; demand\u00e9e&nbsp; par&nbsp; l\u2019Etat&nbsp; marocain&nbsp; est&nbsp; la&nbsp; cr\u00e9ation d\u2019emplois, Renault en aurait cr\u00e9\u00e9 environ 10&nbsp;000, mais \u00e0 quel prix!&nbsp;<\/em><em>L\u2019automobile&nbsp; est&nbsp; devenue,&nbsp; en&nbsp; quelques&nbsp; ann\u00e9es,&nbsp; le premier secteur exportateur, devant les phosphates, et l\u2019Etat ne re\u00e7oit quasiment aucune entr\u00e9e fiscale directe de ce secteur<\/em>\u00bb, indique l\u2019ONG.<\/p>\n\n\n\n<p>Des&nbsp; chercheurs&nbsp; du r\u00e9seau Tax Justice Network&nbsp; ont&nbsp; estim\u00e9&nbsp; \u00e0&nbsp; 24,5&nbsp; milliards de dirhams (2,5 milliards&nbsp;$) par an les pertes fiscales subies par le Maroc, rien que par le fait des pratiques fiscales des multinationales.&nbsp;D\u2019apr\u00e8s Oxfam, cela&nbsp; repr\u00e9sente 2,34% du PIB soit l\u2019\u00e9quivalent de 40 centres hospitaliers.<\/p>\n\n\n\n<p>Cette inaction du gouvernement pour r\u00e9duire l\u2019ampleur du ph\u00e9nom\u00e8ne a d\u2019ailleurs pouss\u00e9 l\u2019Union europ\u00e9enne \u00e0 placer le royaume ch\u00e9rifien sur sa liste grise des paradis fiscaux. Un cas qui pourrait rappeler celui de l\u2019\u00eele Maurice, qui a d\u00e9velopp\u00e9 son secteur industriel gr\u00e2ce aux nombreuses exon\u00e9rations fiscales pratiqu\u00e9es dans ses zones franches, et qui figurait encore, jusqu\u2019au 10 octobre dernier, sur la liste grise europ\u00e9enne des paradis fiscaux.<\/p>\n\n\n\n<p>Les exemples de pays comme le Maroc ou l\u2019\u00eele Maurice illustrent le potentiel significatif qu\u2019offrent les zones franches en mati\u00e8re d\u2019industrialisation. Cependant, les \u00e9checs de pays comme le S\u00e9n\u00e9gal avec la zone franche de Mbao, ou les difficult\u00e9s \u00e9prouv\u00e9es par le Togo \u00e0 atteindre les 100&nbsp;000 emplois pr\u00e9vus dans le cadre de sa zone franche lanc\u00e9e en 1990, montrent que les pays africains sont encore loin d\u2019avoir trouv\u00e9 la bonne formule pour faire d\u00e9coller leurs industries.<\/p>\n\n\n\n<p>Pour certains experts, cette situation est due au manque de sp\u00e9cialisation des premi\u00e8res zones franches mises en place sur le continent africain. Pour d\u2019autres, tels que Arkebe Oqubay, conseiller sp\u00e9cial du Premier ministre \u00e9thiopien Abiy Ahmed, ces \u00e9checs sont dus au fait que ces zones \u00abne disposaient pas de services de base tels que l&#8217;\u00e9lectricit\u00e9, l&#8217;eau et les services \u00e0 guichet unique, et n&#8217;\u00e9taient pas align\u00e9es sur la strat\u00e9gie de d\u00e9veloppement national\u00bb.\u00a0Des lacunes que pourraient \u00eatre combl\u00e9es avec l\u2019appui de pays tels que la Chine, la Cor\u00e9e du Sud ou encore les Emirats arabes unis, qui investissent de plus en plus, en Afrique, dans la construction de zones franches, de parcs industriels et de zones \u00e9conomiques sp\u00e9ciales plus performantes et mieux positionn\u00e9es.<\/p>\n\n\n\n<p><a href=\"https:\/\/agenceecofin.com\/hebdop3\/1111-70983-zones-franches-africaines-faut-il-renoncer-aux-rentrees-fiscales-pour-industrialiser-et-creer-des-emplois\">Leia mais<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><small> 7 minutos<\/small> Les premi\u00e8res zones \u00e9conomiques sp\u00e9ciales (ZES) et les zones franches ont \u00e9t\u00e9 mises en place en Afrique, \u00e0 partir des ann\u00e9es 70, suite \u00e0 leur succ\u00e8s dans nombreux pays asiatiques o\u00f9 elles avaient facilit\u00e9 l\u2019industrialisation. Cette strat\u00e9gie a connu un regain d\u2019int\u00e9r\u00eat en Afrique, au cours des derni\u00e8res ann\u00e9es. D\u2019apr\u00e8s l\u2019Organisation internationale du travail (OIT), on d\u00e9nombrait en 1997, seulement 47 zones franches sur l\u2019ensemble du continent africain. Aujourd\u2019hui, on d\u00e9nombre plus de 200 zones \u00e9conomiques sp\u00e9ciales et zones franches, \u00e0 travers <a href=\"https:\/\/www.abrazpe.org.br\/index.php\/2019\/11\/17\/zones-franches-africaines-faut-il-renoncer-aux-rentrees-fiscales-pour-industrialiser-et-creer-des-emplois\/\" class=\"more-link\"><span>Continue lendo<\/span>\u2192<\/a><\/p>\n","protected":false},"author":4,"featured_media":3345,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["entry","author-adm_hb2018","post-3344","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/3344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=3344"}],"version-history":[{"count":1,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/3344\/revisions"}],"predecessor-version":[{"id":3346,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/3344\/revisions\/3346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media\/3345"}],"wp:attachment":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=3344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=3344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=3344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}