{"id":3498,"date":"2020-02-07T17:04:00","date_gmt":"2020-02-07T20:04:00","guid":{"rendered":"https:\/\/www.abrazpe.org.br\/?p=3498"},"modified":"2020-02-07T17:04:02","modified_gmt":"2020-02-07T20:04:02","slug":"industria-de-plastico-biodegradavel-tem-aval-do-ministerio-da-economia","status":"publish","type":"post","link":"https:\/\/www.abrazpe.org.br\/index.php\/2020\/02\/07\/industria-de-plastico-biodegradavel-tem-aval-do-ministerio-da-economia\/","title":{"rendered":"Ind\u00fastria de pl\u00e1stico biodegrad\u00e1vel tem aval do Minist\u00e9rio da Economia"},"content":{"rendered":"<p class=\"estimated-read-time\">Tempo de leitura:<small> 1 minuto<\/small><\/p> \n<p>O Minist\u00e9rio da Economia aprovou o primeiro projeto industrial da Zona de Processamento de Exporta\u00e7\u00e3o (ZPE) implantada no munic\u00edpio de Bataguassu. A partir disso, Mato Grosso do Sul passa a contar com uma ZPE ativa e a primeira ind\u00fastria de pl\u00e1stico biodegrad\u00e1vel a partir da batata doce.&nbsp;<\/p>\n\n\n\n<p>Titular da Semagro (Secretaria de Meio Ambiente, Desenvolvimento Econ\u00f4mico, Produ\u00e7\u00e3o e Agricultura Familiar), o secret\u00e1rio Jaime Verruck explica que Zona de Processamento de Exporta\u00e7\u00e3o \u00e9 um espa\u00e7o onde as ind\u00fastrias operam com benef\u00edcios tribut\u00e1rios, cambiais e administrativos, com contrapartida de exportar no m\u00ednimo 80% da produ\u00e7\u00e3o. \u201cEste \u00e9 um pontap\u00e9 inicial muito importante para que outras ind\u00fastrias venham se instalar na ZPE de Bataguassu, que \u00e9 um empreendimento privado. Mato Grosso do Sul passar\u00e1 a ter uma ind\u00fastria de tecnologia inovadora e diferenciada, na linha em que o mundo est\u00e1 demandando\u201d, explica o secret\u00e1rio.&nbsp;<\/p>\n\n\n\n<p>A ind\u00fastria vai exportar xarope de dextrose de batata doce e maltodextrina de batata doce e tem 90 dias a partir da publica\u00e7\u00e3o da aprova\u00e7\u00e3o para iniciar a instala\u00e7\u00e3o na ZPE. A ZPE de Bataguassu pertence ao grupo EGEZPE, possui uma \u00e1rea total de 2 milh\u00f5es de m\u00b2 com capacidade de duplicar a \u00e1rea, que \u00e9 totalmente alfandegada. Desde 2015 o Governo do Estado trabalha ativamente para a ativa\u00e7\u00e3o da ZPE em Bataguassu, por acreditar na import\u00e2ncia do empreendimento para a economia regional e o potencial para levar Mato Grosso do Sul a novos mercados externos.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.diariodigital.com.br\/economia\/industria-de-plastico-biodegradavel-tem-aval-do-ministerio-da-economia\/191259\/\">Leia mais<\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p><small> 1 minuto<\/small> O Minist\u00e9rio da Economia aprovou o primeiro projeto industrial da Zona de Processamento de Exporta\u00e7\u00e3o (ZPE) implantada no munic\u00edpio de Bataguassu. A partir disso, Mato Grosso do Sul passa a contar com uma ZPE ativa e a primeira ind\u00fastria de pl\u00e1stico biodegrad\u00e1vel a partir da batata doce.&nbsp; Titular da Semagro (Secretaria de Meio Ambiente, Desenvolvimento Econ\u00f4mico, Produ\u00e7\u00e3o e Agricultura Familiar), o secret\u00e1rio Jaime Verruck explica que Zona de Processamento de Exporta\u00e7\u00e3o \u00e9 um espa\u00e7o onde as ind\u00fastrias operam com benef\u00edcios tribut\u00e1rios, cambiais <a href=\"https:\/\/www.abrazpe.org.br\/index.php\/2020\/02\/07\/industria-de-plastico-biodegradavel-tem-aval-do-ministerio-da-economia\/\" class=\"more-link\"><span>Continue lendo<\/span>\u2192<\/a><\/p>\n","protected":false},"author":4,"featured_media":3499,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["entry","author-adm_hb2018","post-3498","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/3498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=3498"}],"version-history":[{"count":1,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/3498\/revisions"}],"predecessor-version":[{"id":3500,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/3498\/revisions\/3500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media\/3499"}],"wp:attachment":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=3498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=3498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=3498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}