{"id":3601,"date":"2020-04-08T18:45:28","date_gmt":"2020-04-08T21:45:28","guid":{"rendered":"https:\/\/www.abrazpe.org.br\/?p=3601"},"modified":"2020-04-08T18:45:30","modified_gmt":"2020-04-08T21:45:30","slug":"zpe-ceara-utiliza-tecnologia-para-ajudar-no-combate-ao-covid-19","status":"publish","type":"post","link":"https:\/\/www.abrazpe.org.br\/index.php\/2020\/04\/08\/zpe-ceara-utiliza-tecnologia-para-ajudar-no-combate-ao-covid-19\/","title":{"rendered":"ZPE Cear\u00e1 utiliza tecnologia para ajudar no combate ao Covid-19"},"content":{"rendered":"<p class=\"estimated-read-time\">Tempo de leitura:<small> 2 minutos<\/small><\/p> \n<p class=\"wp-block-paragraph\">A ZPE Cear\u00e1 \u2013 Companhia Administradora da Zona de Processamento de Exporta\u00e7\u00e3o do Cear\u00e1 \u2013 integrante do Complexo do Pec\u00e9m, implementou procedimento mais avan\u00e7ado de acesso aos Gates principais da empresa com identifica\u00e7\u00e3o e verifica\u00e7\u00e3o de dados atrav\u00e9s de smartphones com leitura de QR-Code. A medida foi adotada em fun\u00e7\u00e3o do atual cen\u00e1rio global da Covid-19 e busca evitar a prolifera\u00e7\u00e3o do v\u00edrus no Pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diariamente, transitam pela ZPE Cear\u00e1 quase 500 caminh\u00f5es, transportando materiais e pessoas de diversos lugares e o intuito \u00e9 reduzir o risco de contamina\u00e7\u00e3o, como destaca a gerente de Opera\u00e7\u00f5es da ZPE Cear\u00e1, Karina Bzyl. Os agendamentos de entrada e sa\u00edda de cargas agora s\u00e3o feitos via online, gerando um QR-Code. \u201dNo momento da entrada, a imagem do QR-Code \u00e9 apresentada pelos motoristas e a leitura do mesmo \u00e9 feita por celulares utilizados pela equipe operacional\u201d, explica Bzyl.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A leitura dos c\u00f3digos \u00e9 feita atrav\u00e9s da c\u00e2mera dos smartphones a uma dist\u00e2ncia de at\u00e9 4 metros (2 metros a mais que a recomenda\u00e7\u00e3o sugerida pela OMS) e captada pelo Sica Mobile, app desenvolvido pela ZPE Cear\u00e1. Confirmadas as informa\u00e7\u00f5es e tamb\u00e9m atrav\u00e9s dos aparelhos, as cancelas s\u00e3o abertas para entrada na \u00e1rea alfandegada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O m\u00e9todo n\u00e3o apenas agrega agilidade e efici\u00eancia \u00e0s opera\u00e7\u00f5es como tamb\u00e9m mitiga ao m\u00e1ximo o contato entre colaboradores da empresa e agentes externos, garantindo a seguran\u00e7a de todos que transitam pelo local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo a diretora de Opera\u00e7\u00f5es da ZPE Cear\u00e1, Andr\u00e9a Freitas, a companhia abriga a maior empresa de siderurgia do Norte\/Nordeste, a Companhia Sider\u00fargica do Pec\u00e9m \u2013 CSP, de grande impacto econ\u00f4mico para o Estado, e a White Martins, que fornece oxig\u00eanio para os hospitais.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDesta forma, podemos considerar que nossos servi\u00e7os tamb\u00e9m s\u00e3o essenciais, n\u00e3o podem ser interrompidos, por isso adotamos todas as medidas necess\u00e1rias e dentro dos padr\u00f5es estabelecidos pela Organiza\u00e7\u00e3o Mundial de Sa\u00fade (OMS) para continuar operando\u201d declara a diretora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outras medidas tamb\u00e9m adotadas pela empresa tamb\u00e9m v\u00e3o no sentido de prevenir casos do coronav\u00edrus, como o homeoffice para servidores da \u00e1rea administrativa, o efetivo uso da m\u00e1scara NF95 na \u00e1rea operacional, rigoroso procedimento de higieniza\u00e7\u00e3o do ambiente de trabalho, a instala\u00e7\u00e3o e distribui\u00e7\u00e3o de dispensers para \u00e1lcool em gel de 70%.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstamos mantendo um di\u00e1logo transparente e de conscientiza\u00e7\u00e3o com os nossos colaboradores e as empresas instaladas da ZPE. Este \u00e9 um momento delicado, mas se cada um fizer sua parte podemos continuar operando, contribuindo com o desenvolvimento do Estado e, o mais importante, garantindo a seguran\u00e7a dos que precisam trabalhar e que possibilitam que outros permane\u00e7am em casa\u201d, finaliza Andr\u00e9a Freitas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.ceara.gov.br\/2020\/04\/06\/zpe-ceara-utiliza-tecnologia-para-ajudar-no-combate-ao-covid-19\/\">Leia mais<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><small> 2 minutos<\/small> A ZPE Cear\u00e1 \u2013 Companhia Administradora da Zona de Processamento de Exporta\u00e7\u00e3o do Cear\u00e1 \u2013 integrante do Complexo do Pec\u00e9m, implementou procedimento mais avan\u00e7ado de acesso aos Gates principais da empresa com identifica\u00e7\u00e3o e verifica\u00e7\u00e3o de dados atrav\u00e9s de smartphones com leitura de QR-Code. A medida foi adotada em fun\u00e7\u00e3o do atual cen\u00e1rio global da Covid-19 e busca evitar a prolifera\u00e7\u00e3o do v\u00edrus no Pa\u00eds. Diariamente, transitam pela ZPE Cear\u00e1 quase 500 caminh\u00f5es, transportando materiais e pessoas de diversos lugares e o <a href=\"https:\/\/www.abrazpe.org.br\/index.php\/2020\/04\/08\/zpe-ceara-utiliza-tecnologia-para-ajudar-no-combate-ao-covid-19\/\" class=\"more-link\"><span>Continue lendo<\/span>\u2192<\/a><\/p>\n","protected":false},"author":4,"featured_media":3602,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["entry","author-adm_hb2018","post-3601","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/3601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=3601"}],"version-history":[{"count":1,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/3601\/revisions"}],"predecessor-version":[{"id":3603,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/3601\/revisions\/3603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media\/3602"}],"wp:attachment":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=3601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=3601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=3601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}