{"id":3982,"date":"2020-10-19T18:40:37","date_gmt":"2020-10-19T21:40:37","guid":{"rendered":"https:\/\/www.abrazpe.org.br\/?p=3982"},"modified":"2020-10-19T18:40:38","modified_gmt":"2020-10-19T21:40:38","slug":"investidores-conhecem-potencial-da-zpe-parnaiba-e-planejam-investimentos","status":"publish","type":"post","link":"https:\/\/www.abrazpe.org.br\/index.php\/2020\/10\/19\/investidores-conhecem-potencial-da-zpe-parnaiba-e-planejam-investimentos\/","title":{"rendered":"Investidores conhecem potencial da ZPE Parna\u00edba e planejam investimentos"},"content":{"rendered":"<p class=\"estimated-read-time\">Tempo de leitura:<small> 1 minuto<\/small><\/p> \n<p>Um grupo de empres\u00e1rios do ramo de exporta\u00e7\u00e3o esteve na ZPE Parna\u00edba nesta quinta-feira (15), acompanhados pela superante de Parcerias e Concess\u00f5es do Governo do Estado do Piau\u00ed, Viviane Moura. O interesse deles era o de conhecer as oportunidades de investimentos no litoral do Piau\u00ed, incluindo a Zona de Processamento de Exporta\u00e7\u00e3o, onde duas empresas j\u00e1 est\u00e3o instaladas e uma delas j\u00e1 \u00e9 a maior exportadora brasileira de cera de carna\u00faba.<\/p>\n\n\n\n<p>Os empres\u00e1rios foram recepcionados pelo presidente Paulo Roberto Cardoso e pelo assessor t\u00e9cnico Djalma Lacerda que fizeram uma explana\u00e7\u00e3o sobre o modelo de funcionamento da ZPE e como as empresas podem nela se instalar com foco nas exporta\u00e7\u00f5es, embora possam tamb\u00e9m comercializar uma parte da produ\u00e7\u00e3o no mercado interno.<\/p>\n\n\n\n<p>Entre os empres\u00e1rios presentes estavam&nbsp;<strong>Igor Elias<\/strong>, do grupo Phenom Investimentos;&nbsp;<strong>Germano Lincoln<\/strong>&nbsp;e&nbsp;<strong>Roberto Perez J\u00fanior<\/strong>, do grupo Key West Capital; e&nbsp;<strong>Anderson Moura<\/strong>, do Grupo Bandeirantes. Para o presidente da ZPE, Paulo Cardoso, a presen\u00e7a dos investidores coincide com o esfor\u00e7o da companhia na \u00e1rea de atra\u00e7\u00e3o de investimentos e indica que a zona de processamento de exporta\u00e7\u00e3o do Piau\u00ed vem despertando o interesse de grandes grupos. &nbsp;\u201cA ZPE Parna\u00edba j\u00e1 \u00e9 uma realidade. Duas ind\u00fastrias j\u00e1 est\u00e3o funcionando e uma delas atingiu o patamar de maior exportadora de cera de carna\u00faba do pa\u00eds, e essa viabilidade econ\u00f4mica que tem atra\u00eddo a aten\u00e7\u00e3o de investidores\u201d, disse.<\/p>\n\n\n\n<p>Algumas horas antes de receber o grupo de empres\u00e1rios da Phenom Investimentos, Key West Capital e Bandeirantes, Paulo Cardoso e equipe t\u00e9cnica da ZPE j\u00e1 haviam recebido um grupo de empres\u00e1rios belgas pesquisando sobre oportunidades de investimentos na \u00e1rea industrial de alimentos. \u201cA ZPE j\u00e1 est\u00e1 gerando empregos e riquezas, sendo o futuro bastante promissor\u201d, comemorou.<\/p>\n\n\n\n<p><a href=\"https:\/\/portalcostanorte.com\/investidores-conhecem-potencial-da-zpe-parnaiba-e-planejam-investimentos\/\">Leia mais<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><small> 1 minuto<\/small> Um grupo de empres\u00e1rios do ramo de exporta\u00e7\u00e3o esteve na ZPE Parna\u00edba nesta quinta-feira (15), acompanhados pela superante de Parcerias e Concess\u00f5es do Governo do Estado do Piau\u00ed, Viviane Moura. O interesse deles era o de conhecer as oportunidades de investimentos no litoral do Piau\u00ed, incluindo a Zona de Processamento de Exporta\u00e7\u00e3o, onde duas empresas j\u00e1 est\u00e3o instaladas e uma delas j\u00e1 \u00e9 a maior exportadora brasileira de cera de carna\u00faba. Os empres\u00e1rios foram recepcionados pelo presidente Paulo Roberto Cardoso e pelo <a href=\"https:\/\/www.abrazpe.org.br\/index.php\/2020\/10\/19\/investidores-conhecem-potencial-da-zpe-parnaiba-e-planejam-investimentos\/\" class=\"more-link\"><span>Continue lendo<\/span>\u2192<\/a><\/p>\n","protected":false},"author":4,"featured_media":3983,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["entry","author-adm_hb2018","post-3982","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/3982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=3982"}],"version-history":[{"count":1,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/3982\/revisions"}],"predecessor-version":[{"id":3984,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/3982\/revisions\/3984"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media\/3983"}],"wp:attachment":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=3982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=3982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=3982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}