{"id":5744,"date":"2023-06-29T10:00:00","date_gmt":"2023-06-29T13:00:00","guid":{"rendered":"https:\/\/www.abrazpe.org.br\/?p=5744"},"modified":"2023-06-28T10:40:53","modified_gmt":"2023-06-28T13:40:53","slug":"estudo-inedito-revela-perfil-das-empresas-exportadoras-brasileiras","status":"publish","type":"post","link":"https:\/\/www.abrazpe.org.br\/index.php\/2023\/06\/29\/estudo-inedito-revela-perfil-das-empresas-exportadoras-brasileiras\/","title":{"rendered":"Estudo revela perfil das empresas exportadoras brasileiras"},"content":{"rendered":"<p class=\"estimated-read-time\">Tempo de leitura:<small> 4 minutos<\/small><\/p> \n<p>A Secretaria de Com\u00e9rcio Exterior (Secex) do Minist\u00e9rio do Desenvolvimento, Ind\u00fastria, Com\u00e9rcio e Servi\u00e7os (MDIC) divulgou um estudo abrangente sobre o com\u00e9rcio exterior brasileiro. Intitulado &#8220;Perfil das Firmas Exportadoras Brasileiras &#8211; Um Panorama&#8221;, o estudo tem como objetivo mapear os desafios enfrentados pelas empresas brasileiras que buscam atuar no mercado internacional, a fim de impulsionar a competitividade do pa\u00eds.<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.gov.br\/mdic\/pt-br\/assuntos\/noticias\/2023\/junho\/perfil_exportadoras-secex.pdf\/@@download\/file\" data-type=\"URL\" data-id=\"https:\/\/www.gov.br\/mdic\/pt-br\/assuntos\/noticias\/2023\/junho\/perfil_exportadoras-secex.pdf\/@@download\/file\" target=\"_blank\" rel=\"noreferrer noopener\">CLIQUE E ACESSE O ESTUDO COMPLETO<\/a><\/strong><\/p>\n\n\n\n<p>O levantamento realizado pela Secex oferece uma radiografia detalhada das empresas exportadoras no Brasil, revelando sua localiza\u00e7\u00e3o, os principais mercados de destino e suas caracter\u00edsticas distintas em compara\u00e7\u00e3o com as empresas n\u00e3o-exportadoras. Al\u00e9m disso, o estudo analisa a din\u00e2mica de entrada e perman\u00eancia dessas empresas no com\u00e9rcio internacional.<\/p>\n\n\n\n<p>As informa\u00e7\u00f5es apresentadas no estudo s\u00e3o de grande relev\u00e2ncia para agentes p\u00fablicos e privados envolvidos no desenvolvimento de pol\u00edticas e estrat\u00e9gias de internacionaliza\u00e7\u00e3o das empresas brasileiras. Tatiana Prazeres, secret\u00e1ria de Com\u00e9rcio Exterior do MDIC, destaca que o diagn\u00f3stico identifica os desafios a serem superados para aumentar o n\u00famero de empresas exportadoras. A reforma tribut\u00e1ria \u00e9 apontada como uma medida fundamental para tornar a produ\u00e7\u00e3o nacional mais competitiva e evitar a exporta\u00e7\u00e3o de tributos.<\/p>\n\n\n\n<p>Herlon Brand\u00e3o, Diretor de Planejamento e Intelig\u00eancia Comercial da Secex, ressalta a crescente demanda por informa\u00e7\u00f5es sobre o com\u00e9rcio internacional por caracter\u00edsticas de empresas. Ele destaca que o Brasil est\u00e1 entre os primeiros pa\u00edses a disponibilizar esses dados, o que mostra sua capacidade de produ\u00e7\u00e3o de informa\u00e7\u00f5es relevantes para o com\u00e9rcio exterior. A Secex tamb\u00e9m integra o grupo de especialistas das Na\u00e7\u00f5es Unidas respons\u00e1vel pela cria\u00e7\u00e3o de um manual internacional com recomenda\u00e7\u00f5es para a produ\u00e7\u00e3o sistem\u00e1tica de dados comerciais por caracter\u00edsticas de empresas.<\/p>\n\n\n\n<p>O estudo revela que apenas 1% das empresas brasileiras realizam exporta\u00e7\u00f5es, totalizando cerca de 25 mil empresas que j\u00e1 conquistaram seu espa\u00e7o no mercado externo. Essas empresas s\u00e3o respons\u00e1veis por aproximadamente 15% dos empregos formais no pa\u00eds. A Am\u00e9rica Latina \u00e9 o principal destino de neg\u00f3cios para a maioria (61%) das empresas exportadoras, destacando a import\u00e2ncia da integra\u00e7\u00e3o regional. Acordos comerciais na regi\u00e3o contribuem para a redu\u00e7\u00e3o de tarifas sobre produtos brasileiros.<\/p>\n\n\n\n<p>O tamanho do mercado consumidor tamb\u00e9m se mostra um fator relevante na escolha do pa\u00eds de destino das exporta\u00e7\u00f5es. Entre 2018 e 2020, houve um aumento de 24% no n\u00famero de empresas exportando para a China, 21% para os EUA e 16% para a Uni\u00e3o Europeia. No entanto, o n\u00famero de empresas exportando para o Mercosul teve um crescimento de apenas 2%.<\/p>\n\n\n\n<p>O estudo destaca que as empresas exportadoras pagam sal\u00e1rios mais altos, contratam mais funcion\u00e1rios e possuem uma propor\u00e7\u00e3o maior de trabalhadores com ensino superior em compara\u00e7\u00e3o com as empresas n\u00e3o-exportadoras. O pr\u00eamio salarial varia de 36% a 124%, dependendo do setor de atividade da empresa.<\/p>\n\n\n\n<p>Em rela\u00e7\u00e3o \u00e0 continuidade das exporta\u00e7\u00f5es, aproximadamente 65% das empresas que iniciam as vendas externas conseguem mant\u00ea-las ap\u00f3s o primeiro ano. No entanto, a maioria das empresas exporta de forma espor\u00e1dica, e os per\u00edodos de exporta\u00e7\u00f5es cont\u00ednuas t\u00eam uma dura\u00e7\u00e3o m\u00e9dia de 3 anos.<\/p>\n\n\n\n<p>O estudo tamb\u00e9m revela que as empresas exportadoras est\u00e3o concentradas em regi\u00f5es espec\u00edficas do Brasil, sendo que 54% delas est\u00e3o localizadas nos estados de S\u00e3o Paulo e Rio Grande do Sul. A regi\u00e3o Sul e Sudeste apresenta um percentual quase 2,5 vezes maior de empresas exportadoras para o Mercosul em compara\u00e7\u00e3o com as regi\u00f5es Norte, Nordeste e Centro-Oeste. As exportadoras das regi\u00f5es Norte, Nordeste e Centro-Oeste possuem uma m\u00e9dia de 30% mais funcion\u00e1rios do que as estabelecidas no Sul e Sudeste.<\/p>\n\n\n\n<p>A Secex destaca a import\u00e2ncia de entender a din\u00e2mica das empresas exportadoras para estimular a participa\u00e7\u00e3o do Brasil no com\u00e9rcio exterior. A facilita\u00e7\u00e3o do com\u00e9rcio, o est\u00edmulo \u00e0 cultura exportadora e a promo\u00e7\u00e3o comercial, especialmente para micro, pequenas e m\u00e9dias empresas, est\u00e3o entre as prioridades da secretaria. Al\u00e9m disso, o governo federal trabalha na conclus\u00e3o do Portal \u00danico de Com\u00e9rcio Exterior at\u00e9 2026, com o objetivo de aprimorar processos, integrar sistemas e reduzir burocracia, custos e prazos para os operadores de com\u00e9rcio exterior. A amplia\u00e7\u00e3o da base exportadora trar\u00e1 benef\u00edcios concretos para o desenvolvimento econ\u00f4mico do Brasil.<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Foto: Pixabay<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><small> 4 minutos<\/small> A Secretaria de Com\u00e9rcio Exterior (Secex) do Minist\u00e9rio do Desenvolvimento, Ind\u00fastria, Com\u00e9rcio e Servi\u00e7os (MDIC) divulgou um estudo abrangente sobre o com\u00e9rcio exterior brasileiro. Intitulado &#8220;Perfil das Firmas Exportadoras Brasileiras &#8211; Um Panorama&#8221;, o estudo tem como objetivo mapear os desafios enfrentados pelas empresas brasileiras que buscam atuar no mercado internacional, a fim de impulsionar a competitividade do pa\u00eds. CLIQUE E ACESSE O ESTUDO COMPLETO O levantamento realizado pela Secex oferece uma radiografia detalhada das empresas exportadoras no Brasil, revelando sua localiza\u00e7\u00e3o, <a href=\"https:\/\/www.abrazpe.org.br\/index.php\/2023\/06\/29\/estudo-inedito-revela-perfil-das-empresas-exportadoras-brasileiras\/\" class=\"more-link\"><span>Continue lendo<\/span>\u2192<\/a><\/p>\n","protected":false},"author":6,"featured_media":5745,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[72,80,106,107,74],"class_list":["entry","author-fpx","post-5744","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","tag-abrazpe","tag-comercio-exterior","tag-governo-federal","tag-secex","tag-zpe"],"_links":{"self":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/5744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=5744"}],"version-history":[{"count":2,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/5744\/revisions"}],"predecessor-version":[{"id":5747,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/5744\/revisions\/5747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media\/5745"}],"wp:attachment":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=5744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=5744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=5744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}