{"id":6953,"date":"2024-09-16T09:06:41","date_gmt":"2024-09-16T12:06:41","guid":{"rendered":"https:\/\/www.abrazpe.org.br\/?p=6953"},"modified":"2024-09-16T09:06:42","modified_gmt":"2024-09-16T12:06:42","slug":"fiemt-e-casa-da-industria-de-caceres-discutem-desenvolvimento-industrial-da-regiao","status":"publish","type":"post","link":"https:\/\/www.abrazpe.org.br\/index.php\/2024\/09\/16\/fiemt-e-casa-da-industria-de-caceres-discutem-desenvolvimento-industrial-da-regiao\/","title":{"rendered":"Fiemt e Casa da Ind\u00fastria de C\u00e1ceres discutem desenvolvimento industrial da regi\u00e3o"},"content":{"rendered":"<p class=\"estimated-read-time\">Tempo de leitura:<small> 2 minutos<\/small><\/p> \n<p><a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&amp;url=https%3A%2F%2Ffiemt.ind.br%2Fnoticias%2F4551%2Ffiemt-e-casa-da-industria-de-caceres-discutem-desenvolvimento-industrial-da-regiao&amp;title=Fiemt%20e%20Casa%20da%20Ind%C3%BAstria%20de%20C%C3%A1ceres%20discutem%20desenvolvimento%20industrial%20da%20regi%C3%A3o%20-%20Federa%C3%A7%C3%A3o%20das%20Ind%C3%BAstrias%20do%20Estado%20de%20Mato%20Grosso&amp;summary=Comitiva%20do%20Sistema%20Fiemt%20visitou%20as%20instala%C3%A7%C3%B5es%20da%20ZPE%20de%20Mato%20Grosso%20com%20os%20presidentes%20dos%20tr%C3%AAs%20sindicatos%20industriais%20da%20regi%C3%A3o%20sudoeste%0A\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p>Nesta quinta-feira (12), a Federa\u00e7\u00e3o das Ind\u00fastrias do Estado de Mato Grosso (Fiemt), junto com os sindicatos industriais da Casa da Ind\u00fastria de C\u00e1ceres, realizou uma reuni\u00e3o estrat\u00e9gica para debater o desenvolvimento industrial da regi\u00e3o, com foco especial na Zona de Processamento de Exporta\u00e7\u00e3o (ZPE). A proposta da Fiemt \u00e9 a realiza\u00e7\u00e3o de um estudo e planejamento estrat\u00e9gico industrial para a \u00e1rea, visando atrair investimentos e fortalecer a infraestrutura local.<\/p>\n\n\n\n<p>A ZPE foi destacada como uma pe\u00e7a importante para o desenvolvimento, mas n\u00e3o isolada. Segundo o presidente em exerc\u00edcio da Fiemt, Gustavo de Oliveira, o desenvolvimento da regi\u00e3o tamb\u00e9m depende de um conjunto de fatores, como a implementa\u00e7\u00e3o de um distrito industrial eficiente, melhorias em energia, transporte, log\u00edstica e conectividade digital.<\/p>\n\n\n\n<p>Recentemente, Gustavo de Oliveira e a superintendente da Fiemt, Fernanda Campos, visitaram o Observat\u00f3rio da Ind\u00fastria da Federa\u00e7\u00e3o das Ind\u00fastrias do Estado do Cear\u00e1 (FIEC), um dos mais renomados do pa\u00eds, que conduziu o estudo de viabilidade da ZPE cearense, que este ano completou 10 anos de exist\u00eancia. A visita incluiu uma an\u00e1lise da estrutura do porto de Pec\u00e9m, que est\u00e1 conectado \u00e0 ZPE local.<\/p>\n\n\n\n<p>Durante a reuni\u00e3o em C\u00e1ceres, o grupo visitou as instala\u00e7\u00f5es da ZPE, sendo recebebidos pelo presidente daAdministradora da ZPE de C\u00e1ceres (AZPEC), Adilson Reis,, que fez uma apresenta\u00e7\u00e3o sobre o hist\u00f3rico do empreendimento, desde a parte t\u00e9ncica da cria\u00e7\u00e3o, at\u00e9 o atual est\u00e1gio. A ZPE j\u00e1 foi homologada pela Receita Federal, e as empresas internacionais interessadas aguardam a aprova\u00e7\u00e3o final do conselho para iniciarem suas opera\u00e7\u00f5es.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"628\" src=\"https:\/\/www.abrazpe.org.br\/wp-content\/uploads\/2024\/09\/Caceres_12_09-1024x628.jpeg\" alt=\"\" class=\"wp-image-6955\" srcset=\"https:\/\/www.abrazpe.org.br\/wp-content\/uploads\/2024\/09\/Caceres_12_09-1024x628.jpeg 1024w, https:\/\/www.abrazpe.org.br\/wp-content\/uploads\/2024\/09\/Caceres_12_09-300x184.jpeg 300w, https:\/\/www.abrazpe.org.br\/wp-content\/uploads\/2024\/09\/Caceres_12_09-768x471.jpeg 768w, https:\/\/www.abrazpe.org.br\/wp-content\/uploads\/2024\/09\/Caceres_12_09-370x227.jpeg 370w, https:\/\/www.abrazpe.org.br\/wp-content\/uploads\/2024\/09\/Caceres_12_09-970x595.jpeg 970w, https:\/\/www.abrazpe.org.br\/wp-content\/uploads\/2024\/09\/Caceres_12_09.jpeg 1365w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Nesta sexta-feira (13), a Fiemt e os sindicatos locais Sinduscon Sudoeste, Sindimec Sudoeste e SIA C\u00e1ceres, realizar\u00e3o um caf\u00e9 da manh\u00e3 com empres\u00e1rios na Casa da Ind\u00fastria de C\u00e1ceres, como parte do esfor\u00e7o para fortalecer a rela\u00e7\u00e3o entre os setores produtivos e discutir as oportunidades para a regi\u00e3o.<\/p>\n\n\n\n<p>Participaram das atividades o vice-presidente da Fiemt Helo\u00edzo Motta, Jos\u00e9 Provid\u00eancia, presidente em exerc\u00edcio Sinduscon Sudoeste, Massao Koga, presidente do Sindimec Sudoeste e Marco Ribeiro, presidente do SIA C\u00e1ceres. Os diretores sindicais, Alfo Caixeta (Sindimec Sudoeste), David Carvalho (Sindimec Sudoeste), Wellington Nunes (SIA), Celso Silva (Sinduscon Sudoeste) e o advogado Bruno Cordova Fran\u00e7a.<\/p>\n\n\n\n<p>Pela Fiemt, tamb\u00e9m participaram a gerente de relacionamento Setorial, Rib\u00ea Souza, gerente do Sesi, Adriana Ter\u00e7ariol, e assessora executiva da Casa da Ind\u00fastria, Cristiane L\u00e1bio.<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Fonte: FIEMT | Foto: Divulga\u00e7\u00e3o\/FIEMT<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><small> 2 minutos<\/small> Nesta quinta-feira (12), a Federa\u00e7\u00e3o das Ind\u00fastrias do Estado de Mato Grosso (Fiemt), junto com os sindicatos industriais da Casa da Ind\u00fastria de C\u00e1ceres, realizou uma reuni\u00e3o estrat\u00e9gica para debater o desenvolvimento industrial da regi\u00e3o, com foco especial na Zona de Processamento de Exporta\u00e7\u00e3o (ZPE). A proposta da Fiemt \u00e9 a realiza\u00e7\u00e3o de um estudo e planejamento estrat\u00e9gico industrial para a \u00e1rea, visando atrair investimentos e fortalecer a infraestrutura local. A ZPE foi destacada como uma pe\u00e7a importante para o desenvolvimento, mas <a href=\"https:\/\/www.abrazpe.org.br\/index.php\/2024\/09\/16\/fiemt-e-casa-da-industria-de-caceres-discutem-desenvolvimento-industrial-da-regiao\/\" class=\"more-link\"><span>Continue lendo<\/span>\u2192<\/a><\/p>\n","protected":false},"author":6,"featured_media":6954,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[72,80,120,74],"class_list":["entry","author-fpx","post-6953","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","tag-abrazpe","tag-comercio-exterior","tag-mato-grosso","tag-zpe"],"_links":{"self":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/6953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=6953"}],"version-history":[{"count":1,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/6953\/revisions"}],"predecessor-version":[{"id":6956,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/6953\/revisions\/6956"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media\/6954"}],"wp:attachment":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=6953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=6953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=6953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}