{"id":7036,"date":"2024-10-11T07:40:40","date_gmt":"2024-10-11T10:40:40","guid":{"rendered":"https:\/\/www.abrazpe.org.br\/?p=7036"},"modified":"2024-10-11T07:40:41","modified_gmt":"2024-10-11T10:40:41","slug":"gonzaga-visita-obras-da-zpe-que-vao-agilizar-exportacao-no-acre","status":"publish","type":"post","link":"https:\/\/www.abrazpe.org.br\/index.php\/2024\/10\/11\/gonzaga-visita-obras-da-zpe-que-vao-agilizar-exportacao-no-acre\/","title":{"rendered":"Gonzaga visita obras da ZPE que v\u00e3o agilizar exporta\u00e7\u00e3o no Acre"},"content":{"rendered":"<p class=\"estimated-read-time\">Tempo de leitura:<small> 2 minutos<\/small><\/p> \n<p><a href=\"https:\/\/ecosdanoticia.net\/2024\/10\/10\/\"><\/a>Ap\u00f3s visitas a autoridades e empres\u00e1rios peruanos que se mostraram interessados em comprar produtos acreanos, o presidente da Assembleia Legislativa do Acre (Aleac), deputado Luiz Gonzaga, acompanhou nesta quinta-feira (10) o andamento das obras de revitaliza\u00e7\u00e3o da Zona de Processamento de Exporta\u00e7\u00e3o (ZPE), local que ser\u00e1 fundamental para agilizar o processo de importa\u00e7\u00e3o e exporta\u00e7\u00e3o dos produtos acreanos para a Am\u00e9rica do Sul e \u00c1sia.<\/p>\n\n\n\n<p>A previs\u00e3o \u00e9 que a primeira parte da revitaliza\u00e7\u00e3o do espa\u00e7o seja entregue at\u00e9 o m\u00eas de novembro deste ano. A expectativa do governo \u00e9 que a ZPE esteja em pleno funcionamento j\u00e1 no in\u00edcio do ano de 2025.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/ac24horas.com\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-10-at-13.17.03-1-scaled.jpeg\" alt=\"\"\/><\/figure>\n\n\n\n<p>Gonzaga, que defende a integra\u00e7\u00e3o comercial entre Acre, Peru, Bol\u00edvia e \u00c1sia como ferramenta de desenvolvimento socioecon\u00f4mico do estado, visitou a ZPE acompanhado do secret\u00e1rio de Obras do Estado, \u00cdtalo Lopes.<\/p>\n\n\n\n<p>O presidente da Aleac se mostrou otimista com o andamento das obras e aproveitou para agradecer ao governador Gladson Cameli pelos investimentos feitos para impulsionar a exporta\u00e7\u00e3o dos produtos acreanos.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/ac24horas.com\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-10-at-13.17.03-2-scaled.jpeg\" alt=\"\"\/><\/figure>\n\n\n\n<p>\u201cFiquei muito contente com o andamento das obras de revitaliza\u00e7\u00e3o da ZPE. Isso \u00e9 muito positivo para o processo de exporta\u00e7\u00e3o dos nossos produtos. Quero parabenizar o governador Gladson pelo compromisso de investir no com\u00e9rcio entre o Acre, Peru, Bol\u00edvia e pa\u00edses da \u00c1sia, assim tamb\u00e9m como o secret\u00e1rio \u00cdtalo que tem feito um bom trabalho. A ZPE \u00e9 muito importante nesse processo de importa\u00e7\u00e3o e exporta\u00e7\u00e3o\u201d, disse.<\/p>\n\n\n\n<p>O secret\u00e1rio \u00cdtalo Lopes afirmou que a revitaliza\u00e7\u00e3o da ZPE \u00e9 uma ordem do governador Gladson Cameli para impulsionar a exporta\u00e7\u00e3o acreana.<\/p>\n\n\n\n<p>\u201cA ZPE \u00e9 uma pauta muito importante para o nosso governador Gladson Cameli. Ent\u00e3o a ZPE foi uma ordem do governador para que a gente desse ordem de servi\u00e7o para a revitaliza\u00e7\u00e3o do espa\u00e7o para que possamos voltar a funcionar aqui na ZPE. A previs\u00e3o \u00e9 de que no in\u00edcio do novembro a setor de administra\u00e7\u00e3o j\u00e1 esteja funcionando. Esse \u00e9 um pedido do governador para ver a ZPE funcionando novamente\u201d, disse \u00cdtalo.<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Fonte\/Fotos: Ecos da Not\u00edcias<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><small> 2 minutos<\/small> Ap\u00f3s visitas a autoridades e empres\u00e1rios peruanos que se mostraram interessados em comprar produtos acreanos, o presidente da Assembleia Legislativa do Acre (Aleac), deputado Luiz Gonzaga, acompanhou nesta quinta-feira (10) o andamento das obras de revitaliza\u00e7\u00e3o da Zona de Processamento de Exporta\u00e7\u00e3o (ZPE), local que ser\u00e1 fundamental para agilizar o processo de importa\u00e7\u00e3o e exporta\u00e7\u00e3o dos produtos acreanos para a Am\u00e9rica do Sul e \u00c1sia. A previs\u00e3o \u00e9 que a primeira parte da revitaliza\u00e7\u00e3o do espa\u00e7o seja entregue at\u00e9 o m\u00eas de <a href=\"https:\/\/www.abrazpe.org.br\/index.php\/2024\/10\/11\/gonzaga-visita-obras-da-zpe-que-vao-agilizar-exportacao-no-acre\/\" class=\"more-link\"><span>Continue lendo<\/span>\u2192<\/a><\/p>\n","protected":false},"author":6,"featured_media":7037,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[72,80,74],"class_list":["entry","author-fpx","post-7036","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","tag-abrazpe","tag-comercio-exterior","tag-zpe"],"_links":{"self":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/7036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=7036"}],"version-history":[{"count":1,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/7036\/revisions"}],"predecessor-version":[{"id":7038,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/7036\/revisions\/7038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media\/7037"}],"wp:attachment":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=7036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=7036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=7036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}