{"id":8439,"date":"2025-11-07T11:25:21","date_gmt":"2025-11-07T14:25:21","guid":{"rendered":"https:\/\/www.abrazpe.org.br\/?p=8439"},"modified":"2025-11-07T11:25:22","modified_gmt":"2025-11-07T14:25:22","slug":"dona-do-tiktok-ganha-aval-para-data-center-na-zpe-de-pecem-no-ceara","status":"publish","type":"post","link":"https:\/\/www.abrazpe.org.br\/index.php\/2025\/11\/07\/dona-do-tiktok-ganha-aval-para-data-center-na-zpe-de-pecem-no-ceara\/","title":{"rendered":"Dona do TikTok ganha aval para data center na ZPE de Pec\u00e9m, no Cear\u00e1"},"content":{"rendered":"<p class=\"estimated-read-time\">Tempo de leitura:<small> 1 minuto<\/small><\/p> \n<p>O Conselho Nacional das Zonas de Processamento de Exporta\u00e7\u00e3o (CZPE) aprovou o projeto da chinesa&nbsp;<strong>Bytedance<\/strong>&nbsp;(dona do&nbsp;<a href=\"https:\/\/teletime.com.br\/tag\/tiktok\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>TikTok<\/strong><\/a>)&nbsp;para atuar na Zona de Processamento de Exporta\u00e7\u00e3o<strong><a href=\"https:\/\/www12.senado.leg.br\/noticias\/entenda-o-assunto\/zpes#:~:text=A%20Zona%20de%20Processamento%20de%20Exporta%C3%A7%C3%A3o%20(ZPE),t%C3%AAm%20tratamento%20tribut%C3%A1rio%2C%20cambial%20e%20administrativo%20diferenciados.\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;(ZPE)<\/a><\/strong>&nbsp;de Pec\u00e9m, localizada em S\u00e3o Gon\u00e7alo do Amarante (CE).<\/p>\n\n\n\n<p>A autoriza\u00e7\u00e3o&nbsp;<strong>permite que a companhia preste servi\u00e7os de armazenamento e processamento de dados voltados exclusivamente ao mercado externo<\/strong>.<\/p>\n\n\n\n<p>A decis\u00e3o foi tomada na 41\u00aa Reuni\u00e3o Ordin\u00e1ria do CZPE, realizada no dia 3 de novembro de 2025, e&nbsp;<a href=\"https:\/\/www.in.gov.br\/en\/web\/dou\/-\/resolucao-czpe\/mdic-n-112-de-3-de-novembro-de-2025-667113133\" target=\"_blank\" rel=\"noreferrer noopener\">publicada oficialmente nesta quinta-feira, 6<\/a>. O projeto segue as diretrizes da Lei n\u00ba 11.508\/2007, que regula o funcionamento das ZPEs \u2014 \u00e1reas de livre com\u00e9rcio destinadas a incentivar exporta\u00e7\u00f5es e atrair investimentos.<\/p>\n\n\n\n<p>Pelas regras estabelecidas, a Bytedance&nbsp;<strong>dever\u00e1 utilizar energia proveniente de fontes renov\u00e1veis em suas opera\u00e7\u00f5es<\/strong>. Al\u00e9m disso, a empresa ter\u00e1 90 dias para constituir a pessoa jur\u00eddica respons\u00e1vel pela implanta\u00e7\u00e3o do projeto e 30 dias adicionais para solicitar formalmente sua instala\u00e7\u00e3o na ZPE.<\/p>\n\n\n\n<p>O projeto, que promete ter grandes propor\u00e7\u00f5es, deve ter a Omnia (empresa do Patria Investimentos) e a Casa dos Ventos como envolvidas, anunciaram as duas empresas nesta semana.<\/p>\n\n\n\n<p>O CZPE refor\u00e7ou que&nbsp;<strong>qualquer altera\u00e7\u00e3o no escopo do projeto<\/strong>&nbsp;<strong>ou nos servi\u00e7os oferecidos precisar\u00e1 de nova aprova\u00e7\u00e3o do \u00f3rg\u00e3o<\/strong>. Caso as condi\u00e7\u00f5es e prazos definidos n\u00e3o sejam cumpridos, a autoriza\u00e7\u00e3o poder\u00e1 ser&nbsp;<strong>revogada<\/strong>.<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Fonte: Teletime | Foto: Pexels<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><small> 1 minuto<\/small> O Conselho Nacional das Zonas de Processamento de Exporta\u00e7\u00e3o (CZPE) aprovou o projeto da chinesa&nbsp;Bytedance&nbsp;(dona do&nbsp;TikTok)&nbsp;para atuar na Zona de Processamento de Exporta\u00e7\u00e3o&nbsp;(ZPE)&nbsp;de Pec\u00e9m, localizada em S\u00e3o Gon\u00e7alo do Amarante (CE). A autoriza\u00e7\u00e3o&nbsp;permite que a companhia preste servi\u00e7os de armazenamento e processamento de dados voltados exclusivamente ao mercado externo. A decis\u00e3o foi tomada na 41\u00aa Reuni\u00e3o Ordin\u00e1ria do CZPE, realizada no dia 3 de novembro de 2025, e&nbsp;publicada oficialmente nesta quinta-feira, 6. O projeto segue as diretrizes da Lei n\u00ba 11.508\/2007, que <a href=\"https:\/\/www.abrazpe.org.br\/index.php\/2025\/11\/07\/dona-do-tiktok-ganha-aval-para-data-center-na-zpe-de-pecem-no-ceara\/\" class=\"more-link\"><span>Continue lendo<\/span>\u2192<\/a><\/p>\n","protected":false},"author":6,"featured_media":8440,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[72,80,508],"class_list":["entry","author-fpx","post-8439","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","tag-abrazpe","tag-comercio-exterior","tag-tik-tok"],"_links":{"self":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/8439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=8439"}],"version-history":[{"count":1,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/8439\/revisions"}],"predecessor-version":[{"id":8441,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/posts\/8439\/revisions\/8441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media\/8440"}],"wp:attachment":[{"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=8439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=8439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abrazpe.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=8439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}